{"id":4740,"date":"2021-03-09T17:12:11","date_gmt":"2021-03-09T16:12:11","guid":{"rendered":"https:\/\/www.mesrideaux.fr\/blog\/?p=4740"},"modified":"2022-03-15T22:21:54","modified_gmt":"2022-03-15T21:21:54","slug":"maison-objet-2021-quoi-de-neuf-sur-la-planete-deco","status":"publish","type":"post","link":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/","title":{"rendered":"Maison &#038; Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ?"},"content":{"rendered":"\r\n<p>A chaque saison son \u00e9dition de Maison &amp; Objet ; on suit et on analyse pour vous !<\/p>\r\n\r\n\r\n\r\n<p>C&rsquo;est parti pour Maison &amp; Objet printemps 2021.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Maison &amp; Objet lance les Digital Days<\/h2>\r\n\r\n\r\n\r\n<p>En raison de la crise de la COVID, le secteur d\u00e9co cherche de nouvelles mani\u00e8res d\u2019exister. Dans ce contexte, \u00ab\u00a0Maison &amp; Objet\u00a0\u00bb, l\u2019\u00e9v\u00e9nement bi-annuel d\u00e9di\u00e9 \u00e0 l\u2019\u00e9quipement de la maison (nouvelles tendances, nouveaux produits), a lanc\u00e9 les \u00ab\u00a0Digital days\u00a0\u00bb en lieu et place de l\u2019habituel salon de Janvier. Un \u00e9v\u00e9nement d\u00e9co digital \u00e9chelonn\u00e9 sur huit semaines, avec un programme de th\u00e9matiques assorti d\u2019 une newsletter sp\u00e9cifique pour ne rien louper.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Etat des lieux du march\u00e9 de la d\u00e9co<\/h2>\r\n\r\n\r\n\r\n<p>La pand\u00e9mie n\u2019a pas affaibli les envies de nouveaut\u00e9s d\u00e9co, au contraire\u00a0: priv\u00e9s de voyages, les particuliers ressentent un besoin de changement, qui prend forme directement dans le cadre de vie. Les confinements et autres couvre-feu favorisent le secteur d\u00e9co (il faut bien souligner les avantages o\u00f9 on peut les trouver\u00a0!), car lorsqu\u2019on a fait le tour de son logement, de petits ajouts ou ajustements peuvent faire la diff\u00e9rence et insuffler un peu de plaisir \u00e0 \u00eatre chez soi, alimenter un regard positif port\u00e9 sur nos vies et nos int\u00e9rieurs. Une v\u00e9ritable n\u00e9cessit\u00e9\u00a0!<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">D\u00e9couvrir les nouveaut\u00e9s d\u00e9co via la plateforme de Maison &amp; Objet\u00a0<\/h2>\r\n\r\n\r\n\r\n<p>Dans un climat tourment\u00e9, la digitalisation du salon Maison &amp; Objet\u00a0appara\u00eet comme un moyen d\u2019\u00e9tudier pos\u00e9ment et efficacement l\u2019offre d\u00e9co saisonni\u00e8re. Une offre distill\u00e9e de fin janvier \u00e0 fin mars 2021, \u00e0 travers de multiples th\u00e9matiques, elles-m\u00eames traduites en moodboards, s\u00e9lections d\u2019influenceurs, web conf\u00e9rences. Les sp\u00e9cialistes des tendances attitr\u00e9s de Maison &amp; Objet, tels Vincent Gr\u00e9goire et Elisabeth Leriche, sont au rendez-vous.<\/p>\r\n\r\n\r\n\r\n<p>Voici ce que, chez MesRideaux.fr, nous retenons de tout cela, et que nous avons envie de vous restituer\u00a0(entre amateurs de d\u00e9co)\u00a0: des produits qui font sens, parce qu\u2019ils racontent de nouvelles histoires, et \/ ou par leur logique durable. Nous vous les pr\u00e9sentons selon deux axes\u00a0: \u00ab\u00a0<span style=\"text-decoration: underline;\">Inattendu et fantaisiste<\/span>\u00a0\u00bb, et \u00ab\u00a0<span style=\"text-decoration: underline;\">Simple et Durable<\/span>\u00a0\u00bb.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Nouveaut\u00e9s d\u00e9co Maison &amp; Objet : Inattendu et fantaisiste<\/h2>\r\n\r\n\r\n\r\n<p>Nos int\u00e9rieurs sont devenus le centre de nos vies quotidiennes. Insuffler \u00e0 nos lieux de vies un suppl\u00e9ment de sens et une dose de bonne humeur est d\u00e8s lors indispensable\u00a0!\u00a0<\/p>\r\n\r\n\r\n\r\n<p>Inventivit\u00e9 des formes, mat\u00e9riaux d\u00e9tourn\u00e9s, couleurs tendres et p\u00e9tillantes, motifs na\u00effs humains et enjou\u00e9s, diffusent une aura de libert\u00e9 et de plaisir. Vive la d\u00e9co feel good\u00a0!<\/p>\r\n\r\n\r\n\r\n<p>Les bo\u00eetes Bento de Takaneka Bento Box nous font envisager des gestes simples \u2013 conditionner la nourriture \u2013 comme un jeu. Les combinaisons des couleurs et des sangles sont un v\u00e9ritable ravissement. Et comme la beaut\u00e9 est loin d\u2019\u00eatre futile, on approuve chaleureusement.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"598\" class=\"wp-image-4741\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-1024x598.png\" alt=\"\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-1024x598.png 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-300x175.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-770x450.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-1536x897.png 1536w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-2048x1196.png 2048w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-293x171.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/takenaka-bento-box-1400x818.png 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\r\n<figcaption><em>Takenaka Bento Box<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Mais dans le registre bonne humeur, on attribue la palme \u00e0 la marque Octaevo, qui revendique la diff\u00e9rence, t\u00e2che de r\u00e9pandre l\u2019originalit\u00e9 \u00e0 travers de modestes petits objets d\u00e9co, se donne pour mission (avec succ\u00e8s !) de diffuser de bonnes vibrations et d\u2019\u00e9gayer les int\u00e9rieurs.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4745\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-829x1024.png\" alt=\"\" width=\"415\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-829x1024.png 829w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-243x300.png 243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-770x952.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-1243x1536.png 1243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-293x362.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo-1400x1730.png 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plateau-en-ceramique-nazar-octaevo.png 1476w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\r\n<figcaption><em>Plateau en c\u00e9ramique Nazar par Octaevo<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Les vases Octaevo, en papier perfor\u00e9 ou en papier d\u00e9cor\u00e9 de motifs graphiques trait\u00e9s en aplats, cr\u00e9ent la surprise et charment par leurs couleurs fraiches et leurs courbes douces. Avec un caract\u00e8re unique combin\u00e9\u00a0\u00a0\u00e0 un aspect fonctionnel, ils sont capables de m\u00e9tamorphoser le look d\u2019un rebord de fen\u00eatre, d\u2019une table d\u2019appoint, d\u2019un dessus de chemin\u00e9e.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4742\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-756x1024.jpg\" alt=\"\" width=\"378\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-756x1024.jpg 756w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-221x300.jpg 221w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-770x1043.jpg 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-1134x1536.jpg 1134w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-293x397.jpg 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1-1400x1897.jpg 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/riviera-paper-vase-wave-big-octaevo-1.jpg 1476w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\r\n<figcaption><em>Vase en papier Octaevo collection Riviera<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4743\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-830x1024.png\" alt=\"vase en papier\" width=\"415\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-830x1024.png 830w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-243x300.png 243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-770x950.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-1245x1536.png 1245w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-293x361.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo-1400x1727.png 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-riviera-octaevo.png 1476w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\r\n<figcaption><em>Vase en papier Octaevo collection Riviera<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4744\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-829x1024.png\" alt=\"\" width=\"415\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-829x1024.png 829w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-243x300.png 243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-770x952.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-1243x1536.png 1243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-293x362.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng-1400x1730.png 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-octaevopng.png 1476w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\r\n<figcaption><em>Vase en papier Hamsa par Octaevo<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4746\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-829x1024.png\" alt=\"\" width=\"415\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-829x1024.png 829w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-243x300.png 243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-770x952.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-1243x1536.png 1243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-293x362.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo-1400x1730.png 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/vase-en-papier-hamsa-2-octaevo.png 1476w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\r\n<figcaption><em>Vase en papier Hamsa par Octaevo<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Les paniers en c\u00e9ramique Sicilia \u2013toujours de la marque Octaevo &#8211; en fa\u00efence tress\u00e9e rehauss\u00e9e d\u2019un gla\u00e7age brillant, sont aussi pratiques que d\u00e9coratifs\u00a0: on a envie d\u2019en disposer un peu partout, dans diff\u00e9rents coloris, au pr\u00e9texte de les remplir de fruits, l\u00e9gumes, friandises ou petits objets.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4747\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01-1024x921.png\" alt=\"\" width=\"512\" height=\"461\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01-1024x921.png 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01-300x270.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01-770x693.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01-293x264.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01-1400x1260.png 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-sicilia-basket-pink-01.png 1476w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\r\n<figcaption><em>Panier en c\u00e9ramique Sicilia par Octaevo<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4760\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-1024x1024.png\" alt=\"\" width=\"512\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-1024x1024.png 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-300x300.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-100x100.png 100w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-770x769.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-293x293.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-390x390.png 390w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-585x585.png 585w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-900x900.png 900w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02-1400x1399.png 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/sicilia-ceramic-basket-green-octaevo-02.png 1476w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\r\n<figcaption><em>Panier en c\u00e9ramique Sicilia par Octaevo<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Enfin, les sculpturales bougies \u00ab\u00a0Templo\u00a0\u00bb d\u2019Octaevo accompagnent chaleureusement et en beaut\u00e9 les mois froids, composant des autels design aux d\u00e9licieuses formes abstraites, \u00e0 la mati\u00e8re polie sensuelle et aux coloris pastel sucr\u00e9s. R\u00e9gressif et voluptueux.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4748\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-829x1024.jpg\" alt=\"\" width=\"415\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-829x1024.jpg 829w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-243x300.jpg 243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-770x952.jpg 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-1243x1536.jpg 1243w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-293x362.jpg 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo-1400x1730.jpg 1400w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bougies-sculptures-octaevo.jpg 1476w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\r\n<figcaption><em>Bougies Templo par Octaevo<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Avec les objets d\u00e9co de la mouvance \u00ab\u00a0inattendu et fantaisiste\u00a0\u00bb, l\u2019int\u00e9rieur devient un territoire d\u2019expression o\u00f9 les objets inspirants suscitent l\u2019inspiration en un cercle vertueux imparable. Une vision du bien \u00eatre, tout en sourires et en \u00e9nergie.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Pour prolonger ce style avec du tissu<\/h3>\r\n\r\n\r\n\r\n<p>Vous avez aim\u00e9 ce th\u00e8me \u00ab\u00a0Inattendu et fantaisiste\u00a0\u00bb\u00a0? Voici quelques tissus \u00e0 motifs vendus sur MesRideaux.fr qui devraient vous plaire aussi.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.mesrideaux.fr\/tissu-au-metre-fao-noir-fond-rouge-sur-lin\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-4771\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/fao-fond-rouge.png\" alt=\"\" width=\"238\" height=\"324\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/fao-fond-rouge.png 476w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/fao-fond-rouge-220x300.png 220w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/fao-fond-rouge-293x399.png 293w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.mesrideaux.fr\/tissu-au-metre-pondichery-fond-vert-menthe-sur-lin\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-4772\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-menthe.png\" alt=\"\" width=\"231\" height=\"329\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-menthe.png 461w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-menthe-210x300.png 210w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-menthe-293x418.png 293w\" sizes=\"(max-width: 231px) 100vw, 231px\" \/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.mesrideaux.fr\/tissu-au-metre-pondichery-fond-framboise-sur-lin\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-4773\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-framboise.png\" alt=\"\" width=\"231\" height=\"329\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-framboise.png 461w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-framboise-210x300.png 210w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/pondichery-framboise-293x418.png 293w\" sizes=\"(max-width: 231px) 100vw, 231px\" \/><\/a><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Nouveaut\u00e9s d\u00e9co Maison &amp; Objet : Simple et durable<\/h2>\r\n\r\n\r\n\r\n<p>Plus que jamais refuge protecteur, la maison r\u00e9clame \u00e0 juste titre confort, douceur des mati\u00e8res, durabilit\u00e9 des mat\u00e9riaux. Les\u00a0\u00a0tons neutres chauds (comme les beiges), les formes enveloppantes organiques, l\u2019artisanat authentique au style minimaliste, permettent d\u2019acc\u00e9der \u00e0 une ambiance sereine, rassurante et faite pour traverser les mois et les ann\u00e9es sans faillir.<\/p>\r\n\r\n\r\n\r\n<p>Dans cette tendance, les objets d\u00e9co portent les valeurs que nous avons envie de d\u00e9fendre, ils apparaissent nobles dans leur naturalit\u00e9 simple, sublim\u00e9e et revendiqu\u00e9e, et nous font ressentir une coh\u00e9rence entre ce que nous sommes et ce qui nous entoure. C\u2019est ce qu\u2019on appelle \u00ab\u00a0se sentir align\u00e9\u00a0! \u00bb Une cr\u00e9ativit\u00e9 responsable \u00e0 base de mat\u00e9riaux durables ou recycl\u00e9s, qui nous fait nous sentir bien.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"text-decoration: underline;\">Quelques exemples\u00a0:<\/span><\/p>\r\n\r\n\r\n\r\n<p>La lampe baladeuse\u00a0en laine recycl\u00e9e issue de fins de pelotes, pompons en raphia et perles de bois K\u00e4vell\u00e4 de Karteko.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"684\" class=\"wp-image-4750\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko--1024x684.png\" alt=\"\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko--1024x684.png 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko--300x201.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko--770x515.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko--370x247.png 370w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko--293x196.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/balladeuse-kavellakarteko-.png 1134w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\r\n<figcaption><em>Baladeuse K\u00e4vell\u00e4, Karteko<\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n<p>Les tasses de Kinta qui mettent en valeur la couleur gris\u00e9e naturelle de l\u2019argile par contraste avec un int\u00e9rieur color\u00e9 et brillant<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4749\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta-1019x1024.png\" alt=\"\" width=\"510\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta-1019x1024.png 1019w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta-300x300.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta-100x100.png 100w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta-770x774.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta-293x294.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/tasses-cyl-gris-argileux-kinta.png 1281w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/>\r\n<figcaption><em>Tasses Cyl en gr\u00e8s argileux, Kinta<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Les vases et pots pour plantes de Kinta faits d&rsquo;un m\u00e9lange de plastique recycl\u00e9 provenant de bouteilles plastiques, de chips de pulpe de bois, et du recyclage de papier de journaux et magasines : un superbe mat\u00e9riau composite, imperm\u00e9able et qui n&rsquo;est pas sans rappeler visuellement le Terrazzo.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"850\" height=\"850\" class=\"wp-image-4761\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA.png\" alt=\"\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA.png 850w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA-300x300.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA-100x100.png 100w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA-770x770.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA-293x293.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA-390x390.png 390w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/plastique-recycle-journaux-recycles-et-pulple-de-bois-KINTA-585x585.png 585w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\r\n<figcaption><em>Collection de vases et cache-pots en mat\u00e9riaux naturels et recycl\u00e9s, Kinta<\/em><\/figcaption>\r\n<\/figure>\r\n\r\n\r\n\r\n\r\n\r\n<p>Le linge de lit, de table et d\u2019office en <a href=\"https:\/\/www.mesrideaux.fr\/rideaux\/lin.html\">lin certifi\u00e9 \u0153ko-tex<\/a> (label \u00e9cologique), de Magic Linen, dans un coloris cannelle chaleureux et naturel.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4751\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/house-de-couette-en-lin-cannelle-magic-linen-683x1024.png\" alt=\"\" width=\"342\" height=\"512\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/house-de-couette-en-lin-cannelle-magic-linen-683x1024.png 683w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/house-de-couette-en-lin-cannelle-magic-linen-200x300.png 200w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/house-de-couette-en-lin-cannelle-magic-linen-770x1154.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/house-de-couette-en-lin-cannelle-magic-linen-293x439.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/house-de-couette-en-lin-cannelle-magic-linen.png 855w\" sizes=\"(max-width: 342px) 100vw, 342px\" \/>\r\n<figcaption><em>Housse de couette en lin cannelle, Magic Linen<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>La vaisselle en bois, notamment celle de Kinta<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" class=\"wp-image-4752\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta-1024x1019.png\" alt=\"\" width=\"512\" height=\"510\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta-1024x1019.png 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta-300x300.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta-100x100.png 100w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta-770x766.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta-293x292.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/bols-et-assiettes-faits-main-en-bois-kinta.png 1284w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\r\n<figcaption><em>Assiettes en bois faites main, Kinta<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p>Les accessoires naturels, recycl\u00e9s, recyclables d\u2019Atelier Costa.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"850\" height=\"886\" class=\"wp-image-4753\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/paniers-en-jute-atelier-costa.png\" alt=\"\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/paniers-en-jute-atelier-costa.png 850w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/paniers-en-jute-atelier-costa-288x300.png 288w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/paniers-en-jute-atelier-costa-770x803.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/paniers-en-jute-atelier-costa-293x305.png 293w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\r\n<figcaption><em>Paniers en jute Atelier Costa<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Pour prolonger ce style avec du tissu<\/h3>\r\n\r\n\r\n\r\n<p>Vous avez aim\u00e9 ce th\u00e8me \u00ab\u00a0Simple et durable\u00bb\u00a0? D\u00e9couvrez sur MesRideaux.fr les <a href=\"https:\/\/www.mesrideaux.fr\/rideaux\/naturels-intemporels.html\" target=\"_blank\" rel=\"noreferrer noopener\">rideaux<\/a>, <a href=\"https:\/\/www.mesrideaux.fr\/tissu-au-metre\/naturels-intemporels.html\" target=\"_blank\" rel=\"noreferrer noopener\">tissus<\/a>, <a href=\"https:\/\/www.mesrideaux.fr\/autres-confections\/coussins\/naturels-intemporels.html\" target=\"_blank\" rel=\"noreferrer noopener\">coussins<\/a> de la cat\u00e9gorie \u00ab\u00a0<strong>naturels intemporels<\/strong>\u00a0\u00bb (mati\u00e8res naturelles et coloris neutres).<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Et pour finir ce tour des nouveaut\u00e9s d\u00e9co \u2026<\/h2>\r\n\r\n\r\n\r\n<p>Terminons avec une derni\u00e8re trouvaille en dehors de ces deux th\u00e8mes, mais en lien avec chacun d\u2019eux.\u00a0\u00a0Il s\u2019agit d\u2019une gamme de lampes \u00e0 luminosit\u00e9 r\u00e9glable, donnant gr\u00e2ce \u00e0 une image tridimensionnelle l\u2019illusion r\u00e9aliste de vraies plantes vertes lumineuses et encadr\u00e9es. De l\u2019innovation cr\u00e9ative et une esth\u00e9tique naturelle, pour un maximum d\u2019effet dans nos int\u00e9rieurs\u00a0!<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"1022\" class=\"wp-image-4756\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-1024x1022.png\" alt=\"\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-1024x1022.png 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-300x300.png 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-100x100.png 100w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-770x768.png 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-293x292.png 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-390x390.png 390w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1-585x585.png 585w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/eclairages-dinterieurs-grow-lampadaires-series-zuiver-1.png 1281w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\r\n<figcaption><em>Eclairages d&rsquo;int\u00e9rieurs grow lampadaires s\u00e9ries, Zuiver<\/em><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>A chaque saison son \u00e9dition de Maison &amp; Objet ; on suit et on analyse pour vous ! C&rsquo;est parti pour Maison &amp; Objet printemps 2021. Maison &amp; Objet lance les Digital Days En raison de la crise de la COVID, le secteur d\u00e9co cherche de nouvelles mani\u00e8res d\u2019exister. Dans ce contexte, \u00ab\u00a0Maison &amp; Objet\u00a0\u00bb, l\u2019\u00e9v\u00e9nement bi-annuel d\u00e9di\u00e9 \u00e0 l\u2019\u00e9quipement de la maison (nouvelles tendances, nouveaux produits), a lanc\u00e9 les \u00ab\u00a0Digital days\u00a0\u00bb en lieu et place de l\u2019habituel salon de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-4740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendances"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maison &amp; Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ? - Mes Rideaux Blog<\/title>\n<meta name=\"description\" content=\"La cellule tendances de MesRideaux.fr d\u00e9crypte Maison &amp; Objet pour vous, \u00e9dition printemps 2021. Les th\u00e8mes qu&#039;on retient en images\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maison &amp; Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ? - Mes Rideaux Blog\" \/>\n<meta property=\"og:description\" content=\"La cellule tendances de MesRideaux.fr d\u00e9crypte Maison &amp; Objet pour vous, \u00e9dition printemps 2021. Les th\u00e8mes qu&#039;on retient en images\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Rideaux Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-09T16:12:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-15T21:21:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1476\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mesrideauxfrBLOG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mesrideauxfrBLOG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/\",\"url\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/\",\"name\":\"Maison & Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ? - Mes Rideaux Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg\",\"datePublished\":\"2021-03-09T16:12:11+00:00\",\"dateModified\":\"2022-03-15T21:21:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804\"},\"description\":\"La cellule tendances de MesRideaux.fr d\u00e9crypte Maison & Objet pour vous, \u00e9dition printemps 2021. Les th\u00e8mes qu'on retient en images\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#primaryimage\",\"url\":\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg\",\"contentUrl\":\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg\",\"width\":1476,\"height\":2000,\"caption\":\"Panier en c\u00e9ramique Sicilia, Ottavo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mesrideaux.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maison &#038; Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#website\",\"url\":\"https:\/\/www.mesrideaux.fr\/blog\/\",\"name\":\"Mes Rideaux Blog\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mesrideaux.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804\",\"name\":\"mesrideauxfrBLOG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g\",\"caption\":\"mesrideauxfrBLOG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maison & Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ? - Mes Rideaux Blog","description":"La cellule tendances de MesRideaux.fr d\u00e9crypte Maison & Objet pour vous, \u00e9dition printemps 2021. Les th\u00e8mes qu'on retient en images","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/","og_locale":"fr_FR","og_type":"article","og_title":"Maison & Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ? - Mes Rideaux Blog","og_description":"La cellule tendances de MesRideaux.fr d\u00e9crypte Maison & Objet pour vous, \u00e9dition printemps 2021. Les th\u00e8mes qu'on retient en images","og_url":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/","og_site_name":"Mes Rideaux Blog","article_published_time":"2021-03-09T16:12:11+00:00","article_modified_time":"2022-03-15T21:21:54+00:00","og_image":[{"width":1476,"height":2000,"url":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg","type":"image\/jpeg"}],"author":"mesrideauxfrBLOG","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mesrideauxfrBLOG","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/","url":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/","name":"Maison & Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ? - Mes Rideaux Blog","isPartOf":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#primaryimage"},"image":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg","datePublished":"2021-03-09T16:12:11+00:00","dateModified":"2022-03-15T21:21:54+00:00","author":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804"},"description":"La cellule tendances de MesRideaux.fr d\u00e9crypte Maison & Objet pour vous, \u00e9dition printemps 2021. Les th\u00e8mes qu'on retient en images","breadcrumb":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#primaryimage","url":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg","contentUrl":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg","width":1476,"height":2000,"caption":"Panier en c\u00e9ramique Sicilia, Ottavo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesrideaux.fr\/blog\/maison-objet-2021-quoi-de-neuf-sur-la-planete-deco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mesrideaux.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Maison &#038; Objet 2021, quoi de neuf sur la plan\u00e8te d\u00e9co ?"}]},{"@type":"WebSite","@id":"https:\/\/www.mesrideaux.fr\/blog\/#website","url":"https:\/\/www.mesrideaux.fr\/blog\/","name":"Mes Rideaux Blog","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesrideaux.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804","name":"mesrideauxfrBLOG","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g","caption":"mesrideauxfrBLOG"}}]}},"acf":[],"jetpack_featured_media_url":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2021\/03\/octaevo-basket-sicilia-blue.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts\/4740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/comments?post=4740"}],"version-history":[{"count":9,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts\/4740\/revisions"}],"predecessor-version":[{"id":5966,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts\/4740\/revisions\/5966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/media\/4757"}],"wp:attachment":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/media?parent=4740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/categories?post=4740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/tags?post=4740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}