{"id":8644,"date":"2024-10-24T11:53:22","date_gmt":"2024-10-24T09:53:22","guid":{"rendered":"https:\/\/www.mesrideaux.fr\/blog\/?p=8644"},"modified":"2024-10-24T11:55:33","modified_gmt":"2024-10-24T09:55:33","slug":"tendance-gonfle","status":"publish","type":"post","link":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/","title":{"rendered":"Tendance : gonfl\u00e9"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-1024x724.jpg\" alt=\"\" class=\"wp-image-8645\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-1024x724.jpg 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-300x212.jpg 300w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-770x544.jpg 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-1536x1086.jpg 1536w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-2048x1448.jpg 2048w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-195x138.jpg 195w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-500x353.jpg 500w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-293x207.jpg 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-1400x990.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Moodboard gonfl\u00e9 par MesRideaux (Tissus Th\u00e9venon et Leli\u00e8vre, Canap\u00e9s Ligne Roset, Sac Miu Miu, Fauteuil Tawla, Peinture Olivier L\u00e9pront).<\/em><\/figcaption><\/figure><\/div>\n\n\n<p><em>D\u00e9tail l\u00e9gendes : <\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Tissu Fairy Light vieux rose, Th\u00e9venon (en haut \u00e0 gauche). Disponible en <a href=\"https:\/\/www.mesrideaux.fr\/tissu-au-metre-fairy-light-fond-vieux-rose\" target=\"_blank\" rel=\"noreferrer noopener\">tissu au m\u00e8tre<\/a> ou confectionn\u00e9 en <a href=\"https:\/\/www.mesrideaux.fr\/rideau-fairy-light-fond-vieux-rose\" target=\"_blank\" rel=\"noreferrer noopener\">produits sur mesure<\/a> par MesRideaux<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Tissu Fjord cognac, Leli\u00e8vre. Disponible en <a href=\"https:\/\/www.mesrideaux.fr\/tissu-au-metre-fjord-cognac\" target=\"_blank\" rel=\"noreferrer noopener\">tissu au m\u00e8tre<\/a> ou confectionn\u00e9 en <a href=\"https:\/\/www.mesrideaux.fr\/coussin-fjord-cognac\" target=\"_blank\" rel=\"noreferrer noopener\">produits sur mesure<\/a> par MesRideaux<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Canap\u00e9 Kashima par Michel Ducaroy re\u0301e\u0301dite\u0301 par Ligne Roset (pr\u00e9sent\u00e9 ici dans deux versions coloris \/ mati\u00e8re).<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Fauteuil Matrice dor\u00e9, Kawla<\/em><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Peinture \u00e0 l&rsquo;huile sur toile \u00ab\u00a0Doudoune bleue\u00a0\u00bb d&rsquo;Olivier L\u00e9pront<\/em><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9finition de la tendance \u00ab\u00a0gonfl\u00e9\u00a0\u00bb<\/h2>\n\n\n\n<p>Promesse de l\u00e9g\u00e8ret\u00e9 mais aussi de confort, dans une id\u00e9e paradoxale et id\u00e9ale du dodu a\u00e9rien et sans poids, le design gonfl\u00e9 se d\u00e9cline de l\u2019ameublement \u00e0 la mode en versions multiples\u00a0: matelass\u00e9, piqu\u00e9, rembourr\u00e9, capitonn\u00e9, empli d\u2019air ou de ouate, en 2D avec des motifs \u00e9vocateurs de la cellule moelleuse et rebondie.<\/p>\n\n\n\n<p>L\u2019univers de la doudoune et du ch\u00e2teau gonflable se rencontrent pour cr\u00e9er un monde de protection ou de surprotection, rassurant au possible, o\u00f9 rien ne heurte ou ne pique, comme si on flottait sur un nuage.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pi\u00e8ces repr\u00e9sentatives de la tendance  \u00ab\u00a0gonfl\u00e9\u00a0\u00bb<\/h2>\n\n\n\n<p>Les pi\u00e8ces mythiques&nbsp;: le canap\u00e9 Kashima, surnomm\u00e9 \u00ab&nbsp;le Chesterfield confortable&nbsp;\u00bb (car sans raideur), cr\u00e9\u00e9 par Michel Ducaroy&nbsp;en 1976 et aujourd\u2019hui r\u00e9\u00e9dit\u00e9 par Ligne Roset, une assise tout mousse avec des lignes galb\u00e9es, arrondies, un confort moelleux, une housse matelass\u00e9e. Mais aussi les doudounes Moncler c\u00f4t\u00e9 mode, auxquelles le jeune peintre fran\u00e7ais hyperr\u00e9aliste Olivier L\u00e9pront rend hommage dans des toiles comme \u00ab&nbsp;Doudoune bleue et \u00ab&nbsp;Doudoune dor\u00e9e&nbsp;\u00bb. Le sac \u00e0 main matelass\u00e9, un classique des accessoires de mode, n\u2019a jamais disparu mais appara\u00eet comme le \u00ab&nbsp;it-bag&nbsp;\u00bb de l\u2019ann\u00e9e 2024, que ce soit en taille mini ou maxi, \u00e0 bandouli\u00e8re, anses, ou version pochette, avec quadrillage simple (carr\u00e9s, losanges) ou plus sophistiqu\u00e9 (exemple de Miu Miu). On doit initialement cette id\u00e9e de sac matelass\u00e9 en cuir \u00e0 la marque Chanel. Ce type de sac \u00e9voque l\u2019\u00e9l\u00e9gance et l\u2019artisanat de haute qualit\u00e9, mais avec une pointe casual, c\u2019est \u00e0 dire confortable, plus d\u00e9contract\u00e9e, et on y revient, un c\u00f4t\u00e9 rassurant.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La t\u00eate de lit gonfl\u00e9e<\/h2>\n\n\n\n<p>Quant \u00e0 la pi\u00e8ce d\u2019ameublement classique pouvant incarner la tendance gonfl\u00e9e \u00e0 la maison, nous pensons \u00e9videmment chez MesRideaux \u00e0 la t\u00eate de lit recouverte de ouate et de textile, surtout dans les types de confection \u00ab&nbsp;Tango&nbsp;\u00bb (capitonnage sur toute la surface de la t\u00eate de lit), \u00ab&nbsp;Extra&nbsp;\u00bb (effet boudins verticaux rembourr\u00e9s), \u00ab&nbsp;Kiss&nbsp;\u00bb (effet cadre avec un pourtour rembourr\u00e9 autour du rectangle central).<\/p>\n\n\n\n<p>Nous vous proposons la confection de votre t\u00eate de lit sur mesure avec l\u2019un des tr\u00e8s nombreux tissus de notre site MesRideaux (sauf ceux qui ne se pr\u00eatent pas \u00e0 cet usage). En pratique, dans la rubrique t\u00eates de lits, vous choisissez d\u2019abord la confection qui vous plait le plus (Tango, Kiss\u2026) puis le tissu (velours, lin, tissu jacquard etc.). En cas de doute, n\u2019h\u00e9sitez pas \u00e0 nous contacter, nous aurons plaisir \u00e0 vous aider et vous conseiller.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.mesrideaux.fr\/tete-de-lit-velours-souple-duchesse-rose-ancien\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-682x1024.jpg\" alt=\"t\u00eate de lit rose\" class=\"wp-image-8293\" srcset=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-682x1024.jpg 682w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-200x300.jpg 200w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-770x1155.jpg 770w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-1024x1536.jpg 1024w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-130x195.jpg 130w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-500x750.jpg 500w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien-293x440.jpg 293w, https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/04\/tissu-au-metre-duchesse-rose-ancien.jpg 1333w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>T\u00eate de lit en velours Duchesse rose ancien<\/em> <em>confection Extra<\/em><\/figcaption><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p>Nous vous souhaitons une saison automne-hiver 2024-25 gonfl\u00e9e, c\u2019est \u00e0 dire l\u00e9g\u00e8re et confortable\u2026 Mais aussi peut-\u00eatre culott\u00e9e, audacieuse&nbsp;?! A bient\u00f4t sur notre blog et notre site d\u00e9di\u00e9s \u00e0 la d\u00e9co textile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9tail l\u00e9gendes : D\u00e9finition de la tendance \u00ab\u00a0gonfl\u00e9\u00a0\u00bb Promesse de l\u00e9g\u00e8ret\u00e9 mais aussi de confort, dans une id\u00e9e paradoxale et id\u00e9ale du dodu a\u00e9rien et sans poids, le design gonfl\u00e9 se d\u00e9cline de l\u2019ameublement \u00e0 la mode en versions multiples\u00a0: matelass\u00e9, piqu\u00e9, rembourr\u00e9, capitonn\u00e9, empli d\u2019air ou de ouate, en 2D avec des motifs \u00e9vocateurs de la cellule moelleuse et rebondie. L\u2019univers de la doudoune et du ch\u00e2teau gonflable se rencontrent pour cr\u00e9er un monde de protection ou de surprotection, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-8644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendances"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tendance : gonfl\u00e9 - Mes Rideaux Blog<\/title>\n<meta name=\"description\" content=\"Avez-vous remarqu\u00e9 ces pi\u00e8ces rebondies, remplies d&#039;air, de mousse, de ouate, qui se r\u00e9pandent dans la mode et la d\u00e9co ? C&#039;est gonfl\u00e9 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tendance : gonfl\u00e9 - Mes Rideaux Blog\" \/>\n<meta property=\"og:description\" content=\"Avez-vous remarqu\u00e9 ces pi\u00e8ces rebondies, remplies d&#039;air, de mousse, de ouate, qui se r\u00e9pandent dans la mode et la d\u00e9co ? C&#039;est gonfl\u00e9 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/\" \/>\n<meta property=\"og:site_name\" content=\"Mes Rideaux Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-24T09:53:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-24T09:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mesrideauxfrBLOG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mesrideauxfrBLOG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/\",\"url\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/\",\"name\":\"Tendance : gonfl\u00e9 - Mes Rideaux Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg\",\"datePublished\":\"2024-10-24T09:53:22+00:00\",\"dateModified\":\"2024-10-24T09:55:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804\"},\"description\":\"Avez-vous remarqu\u00e9 ces pi\u00e8ces rebondies, remplies d'air, de mousse, de ouate, qui se r\u00e9pandent dans la mode et la d\u00e9co ? C'est gonfl\u00e9 !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#primaryimage\",\"url\":\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg\",\"contentUrl\":\"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg\",\"width\":2560,\"height\":1810,\"caption\":\"Moodboard gonfl\u00e9 par MesRideaux (Tissus Th\u00e9venon et Leli\u00e8vre, Canap\u00e9s Ligne Roset, Sac Miu Miu, Fauteuil Tawla, Peinture Olivier L\u00e9pront).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mesrideaux.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tendance : gonfl\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#website\",\"url\":\"https:\/\/www.mesrideaux.fr\/blog\/\",\"name\":\"Mes Rideaux Blog\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mesrideaux.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804\",\"name\":\"mesrideauxfrBLOG\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g\",\"caption\":\"mesrideauxfrBLOG\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tendance : gonfl\u00e9 - Mes Rideaux Blog","description":"Avez-vous remarqu\u00e9 ces pi\u00e8ces rebondies, remplies d'air, de mousse, de ouate, qui se r\u00e9pandent dans la mode et la d\u00e9co ? C'est gonfl\u00e9 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/","og_locale":"fr_FR","og_type":"article","og_title":"Tendance : gonfl\u00e9 - Mes Rideaux Blog","og_description":"Avez-vous remarqu\u00e9 ces pi\u00e8ces rebondies, remplies d'air, de mousse, de ouate, qui se r\u00e9pandent dans la mode et la d\u00e9co ? C'est gonfl\u00e9 !","og_url":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/","og_site_name":"Mes Rideaux Blog","article_published_time":"2024-10-24T09:53:22+00:00","article_modified_time":"2024-10-24T09:55:33+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg","type":"image\/jpeg"}],"author":"mesrideauxfrBLOG","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mesrideauxfrBLOG","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/","url":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/","name":"Tendance : gonfl\u00e9 - Mes Rideaux Blog","isPartOf":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#primaryimage"},"image":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg","datePublished":"2024-10-24T09:53:22+00:00","dateModified":"2024-10-24T09:55:33+00:00","author":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804"},"description":"Avez-vous remarqu\u00e9 ces pi\u00e8ces rebondies, remplies d'air, de mousse, de ouate, qui se r\u00e9pandent dans la mode et la d\u00e9co ? C'est gonfl\u00e9 !","breadcrumb":{"@id":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#primaryimage","url":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg","contentUrl":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg","width":2560,"height":1810,"caption":"Moodboard gonfl\u00e9 par MesRideaux (Tissus Th\u00e9venon et Leli\u00e8vre, Canap\u00e9s Ligne Roset, Sac Miu Miu, Fauteuil Tawla, Peinture Olivier L\u00e9pront)."},{"@type":"BreadcrumbList","@id":"https:\/\/www.mesrideaux.fr\/blog\/tendance-gonfle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mesrideaux.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tendance : gonfl\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.mesrideaux.fr\/blog\/#website","url":"https:\/\/www.mesrideaux.fr\/blog\/","name":"Mes Rideaux Blog","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mesrideaux.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/27c60b0fb63f3b89f288ee64bda16804","name":"mesrideauxfrBLOG","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mesrideaux.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422f6e64a59e8675330c704fe446071c1c8b0c3e40754a3ee5d9cdc27211ba16?s=96&d=mm&r=g","caption":"mesrideauxfrBLOG"}}]}},"acf":[],"jetpack_featured_media_url":"https:\/\/www.mesrideaux.fr\/blog\/wp-content\/uploads\/2024\/10\/planche-gonfle-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts\/8644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/comments?post=8644"}],"version-history":[{"count":3,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts\/8644\/revisions"}],"predecessor-version":[{"id":8650,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/posts\/8644\/revisions\/8650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/media\/8645"}],"wp:attachment":[{"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/media?parent=8644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/categories?post=8644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mesrideaux.fr\/blog\/wp-json\/wp\/v2\/tags?post=8644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}